{"id":15047,"date":"2019-03-14T10:28:53","date_gmt":"2019-03-14T09:28:53","guid":{"rendered":"https:\/\/mguide.eu\/produkt\/sac-sac-a-dos-tbx2-kaki\/"},"modified":"2025-09-02T10:50:26","modified_gmt":"2025-09-02T08:50:26","slug":"sac-sac-a-dos-tb-x2","status":"publish","type":"product","link":"https:\/\/mguide.eu\/fr\/produkt\/sac-sac-a-dos-tb-x2\/","title":{"rendered":"Sac\/Sac \u00e0 dos TBX-2"},"content":{"rendered":"<p>Sac renforc\u00e9 avec mousse de protection pour 77\/50\/49\/48\/45* appareils, con\u00e7u pour \u00eatre utilis\u00e9 par un guide dans une ville ou un mus\u00e9e comme bagage \u00e0 main.<\/p>\n<p>Le sac a une bandouli\u00e8re amovible et des sangles amovibles pour pouvoir l&#8217;utiliser comme sac \u00e0 dos, rang\u00e9s dans une poche sp\u00e9ciale avec fermeture \u00e9clair. Il a aussi deux poign\u00e9es pour le transporter verticalement ou horizontalement, la poign\u00e9e horizontale est double. TBX2 a 3 poches ext\u00e9rieures avec fermeture \u00e9clair : 2 petites \u00e0 l&#8217;avant pour les accessoires et une grande poche \u00e0 l&#8217;arri\u00e8re pour les documents ou les accessoires. \u00c0 l&#8217;int\u00e9rieur du compartiment principal se trouve une poche suppl\u00e9mentaire avec fermeture \u00e9clair.<\/p>\n<p>Il n\u2019est pas recommand\u00e9 de l\u2019envoyer par entreprise de messagerie ou comme bagage a\u00e9rien sans emballage ext\u00e9rieur.<\/p>\n<p>Dimensions (mm) 330 x 445 x 75<\/p>\n<p>* en fonction du syst\u00e8me choisi:<\/p>\n<ul>\n<li>mGuide Pellegrino \u2013 50 u<\/li>\n<li>mGuide Pellegrino 2 \u2013 48 u<\/li>\n<li>Okayo WT-350 \u2013 50 u<\/li>\n<li>Okayo WT-300D &#8211; 45 u<\/li>\n<li>Okayo WT-300G2 \u2013 45 u<\/li>\n<li>Okayo WaveTalk &#8211; 77 u<\/li>\n<li>Okayo OTG-102 &#8211; 49 u<\/li>\n<li>Okayo OTG-200 &#8211; 49 u<\/li>\n<li>Okayo WT-350D &#8211; 50 u<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le sac a une bandouli\u00e8re amovible et des sangles amovibles pour pouvoir l&#8217;utiliser comme sac \u00e0 dos, rang\u00e9s dans une poche sp\u00e9ciale avec fermeture \u00e9clair.<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/mguide.eu\/wp-content\/uploads\/2024\/08\/FR-Nano-Blitz-baner.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-45232\" src=\"https:\/\/mguide.eu\/wp-content\/uploads\/2024\/08\/FR-Nano-Blitz-baner.png\" alt=\"\" width=\"630\" height=\"120\" srcset=\"https:\/\/i0.wp.com\/mguide.eu\/wp-content\/uploads\/2024\/08\/FR-Nano-Blitz-baner.png?w=630&amp;ssl=1 630w, https:\/\/i0.wp.com\/mguide.eu\/wp-content\/uploads\/2024\/08\/FR-Nano-Blitz-baner.png?resize=600%2C114&amp;ssl=1 600w\" sizes=\"auto, (max-width: 630px) 100vw, 630px\" \/><\/a><\/p>\n","protected":false},"featured_media":70874,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[804],"product_tag":[],"class_list":["post-15047","product","type-product","status-publish","has-post-thumbnail","product_cat-sacoches-et-valises-de-transport","pa_marka-mexpo-fr","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"tiered_pricing_type":"fixed","tiered_pricing_fixed_rules":[],"tiered_pricing_product_settings":{"layout":"default","base_unit_name":{"singular":null,"plural":null},"default_variation":null},"tiered_pricing_minimum_quantity":null,"tiered_pricing_roles_data":[],"tiered_pricing_percentage_rules":[],"_links":{"self":[{"href":"https:\/\/mguide.eu\/fr\/wp-json\/wp\/v2\/product\/15047","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mguide.eu\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/mguide.eu\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mguide.eu\/fr\/wp-json\/wp\/v2\/media\/70874"}],"wp:attachment":[{"href":"https:\/\/mguide.eu\/fr\/wp-json\/wp\/v2\/media?parent=15047"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/mguide.eu\/fr\/wp-json\/wp\/v2\/product_brand?post=15047"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/mguide.eu\/fr\/wp-json\/wp\/v2\/product_cat?post=15047"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/mguide.eu\/fr\/wp-json\/wp\/v2\/product_tag?post=15047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}